{"id":22,"count":4,"description":"","link":"https:\/\/www.orkanimpeks.com.mk\/en\/tag\/supply\/","name":"supply","slug":"supply","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>supply Archives - Orkan Impeks<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.orkanimpeks.com.mk\/en\/tag\/supply\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"supply Archives - Orkan Impeks\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.orkanimpeks.com.mk\/en\/tag\/supply\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Orkan Impeks\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.orkanimpeks.com.mk\/tag\/supply\/\",\"url\":\"https:\/\/www.orkanimpeks.com.mk\/tag\/supply\/\",\"name\":\"supply Archives - Orkan Impeks\",\"isPartOf\":{\"@id\":\"https:\/\/www.orkanimpeks.com.mk\/mk\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.orkanimpeks.com.mk\/tag\/supply\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.orkanimpeks.com.mk\/tag\/supply\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.orkanimpeks.com.mk\/mk\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"supply\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.orkanimpeks.com.mk\/mk\/#website\",\"url\":\"https:\/\/www.orkanimpeks.com.mk\/mk\/\",\"name\":\"Orkan Impeks\",\"description\":\"Providing first class transport services\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.orkanimpeks.com.mk\/mk\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"supply Archives - Orkan Impeks","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.orkanimpeks.com.mk\/en\/tag\/supply\/","og_locale":"en_US","og_type":"article","og_title":"supply Archives - Orkan Impeks","og_url":"https:\/\/www.orkanimpeks.com.mk\/en\/tag\/supply\/","og_site_name":"Orkan Impeks","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.orkanimpeks.com.mk\/tag\/supply\/","url":"https:\/\/www.orkanimpeks.com.mk\/tag\/supply\/","name":"supply Archives - Orkan Impeks","isPartOf":{"@id":"https:\/\/www.orkanimpeks.com.mk\/mk\/#website"},"breadcrumb":{"@id":"https:\/\/www.orkanimpeks.com.mk\/tag\/supply\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.orkanimpeks.com.mk\/tag\/supply\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.orkanimpeks.com.mk\/mk\/"},{"@type":"ListItem","position":2,"name":"supply"}]},{"@type":"WebSite","@id":"https:\/\/www.orkanimpeks.com.mk\/mk\/#website","url":"https:\/\/www.orkanimpeks.com.mk\/mk\/","name":"Orkan Impeks","description":"Providing first class transport services","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.orkanimpeks.com.mk\/mk\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.orkanimpeks.com.mk\/en\/wp-json\/wp\/v2\/tags\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orkanimpeks.com.mk\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.orkanimpeks.com.mk\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.orkanimpeks.com.mk\/en\/wp-json\/wp\/v2\/posts?tags=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}